{"id":1963,"date":"2023-03-06T15:45:40","date_gmt":"2023-03-06T14:45:40","guid":{"rendered":"https:\/\/offb.no\/?post_type=tribe_events&#038;p=1963"},"modified":"2023-03-06T15:45:40","modified_gmt":"2023-03-06T14:45:40","slug":"wdno-trening-3-linje-interessenthandtering-2","status":"publish","type":"tribe_events","link":"https:\/\/offb.no\/en\/kalender\/wdno-trening-3-linje-interessenthandtering-2\/","title":{"rendered":"WDNO &#8211; Trening 3 linje ; Interessenth\u00e5ndtering"},"content":{"rendered":"<p>Trening i interessenth\u00e5ndtering for 3 linje<\/p>","protected":false},"excerpt":{"rendered":"<p>Trening i interessenth\u00e5ndtering for 3 linje<\/p>","protected":false},"author":15,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1963","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tribe_events\/1963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/users\/15"}],"version-history":[{"count":1,"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tribe_events\/1963\/revisions"}],"predecessor-version":[{"id":1964,"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tribe_events\/1963\/revisions\/1964"}],"wp:attachment":[{"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/media?parent=1963"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tags?post=1963"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/offb.no\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=1963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}